{"id":2559,"date":"2024-01-22T11:21:52","date_gmt":"2024-01-22T11:21:52","guid":{"rendered":"https:\/\/fromrss.com\/?p=2559"},"modified":"2024-02-19T10:41:14","modified_gmt":"2024-02-19T10:41:14","slug":"2559","status":"publish","type":"post","link":"https:\/\/fromrss.com\/index.php\/2024\/01\/22\/2559\/","title":{"rendered":"Premier jour de la bataille de la Somme"},"content":{"rendered":"\n<audio controls autoplay muted>\n  <source src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/02\/somme.mp3\" type=\"audio\/mpeg\">\n  Your browser does not support the audio element.\n<\/audio><br>\n\n\n\n<p class=\"has-text-align-left\">La commune de Beaumont-Hamel&nbsp;dont la toponymie signifie \u00ab\u00a0joli mont pr\u00e8s d&rsquo;un mar\u00e9cage\u00a0\u00bb est un village tranquille d&rsquo;environ 200 habitants en Picardie, dans le d\u00e9partement de la Somme. Il est situ\u00e9 \u00e0 137 kilom\u00e8tres de Paris Notre-Dame. <\/p>\n\n\n\n<p class=\"has-text-align-left\">La pr\u00e9sence de l&rsquo;homme y est attest\u00e9e depuis longtemps puisqu&rsquo;on y trouve des traces gauloises et romaines, on y construira m\u00eame un ch\u00e2teau au Moyen-Age. En 1914, Beaumont-Hamel est situ\u00e9 sur la ligne de front. Th\u00e9\u00e2tre de violents combats, il ne restera plus rien du village au sortir de la guerre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"649\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare-1024x649.jpg\" alt=\"\" class=\"wp-image-2561\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare-1024x649.jpg 1024w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare-300x190.jpg 300w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare-768x486.jpg 768w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Gare de Beaucourt-Hamel en 1906<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"603\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare2.jpg\" alt=\"\" class=\"wp-image-2562\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare2.jpg 800w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare2-300x226.jpg 300w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/gare2-768x579.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Gare de Beaucourt-Hamel en 1916<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\">A l&rsquo;\u00e9t\u00e9 1914, les Fran\u00e7ais parviennent \u00e0 freiner l&rsquo;avanc\u00e9e de l&rsquo;arm\u00e9e allemande, \u00e0 partir de d\u00e9cembre, les positions d\u00e9fensives commencent \u00e0 se fixer. Le front ne se d\u00e9place plus. Le conflit entre alors dans une nouvelle phase, une guerre clandestine, une guerre de tranch\u00e9es ou les deux arm\u00e9es se font face.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"900\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Race_to_the_Sea_1914.png\" alt=\"\" class=\"wp-image-2560\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Race_to_the_Sea_1914.png 740w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Race_to_the_Sea_1914-247x300.png 247w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>\u00ab\u00a0La course \u00e0 la mer\u00a0\u00bb du 12 septembre au 15 d\u00e9cembre 1914 (3 mois)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\">En 1915, les batailles se concentrent surtout sur l&rsquo;Artois et la Champagne sans faire bouger les lignes. La Somme est \u00e9pargn\u00e9e, la situation y est plut\u00f4t calme. Face \u00e0 l&rsquo;immobilit\u00e9 de cette ligne de front, des deux c\u00f4t\u00e9s, les \u00e9tats-majors envisagent alors de contourner l&rsquo;ennemi par d\u00e9bordement. Le mar\u00e9chal Joffre qui commande les forces Fran\u00e7aises d\u00e9cide \u00e0 Chantilly le 6 d\u00e9cembre 1915 et en accord avec nos alli\u00e9s Britanniques, de mener une grande offensive sur la Somme \u00e0 partir du printemps 1916. L&rsquo;effort devant \u00eatre r\u00e9alis\u00e9 principalement par les Britanniques. A partir de juin commence alors une v\u00e9ritable pluie d&rsquo;obus sur les positions Allemandes, avec en ligne de mire l&rsquo;\u00e9limination des effectifs et du mat\u00e9riel lourd. Les anglais de la 252\u00e8me compagnie reprennent aussi les tunnels commenc\u00e9s par les sapeurs Fran\u00e7ais. Tunnels qu&rsquo;ils vont lourdement miner dans l&rsquo;espoir d&rsquo;ouvrir des br\u00e8ches dans la d\u00e9fense des lignes adverses. <\/p>\n\n\n\n<p class=\"has-text-align-left\">Entre avril et juin 1916, la 252\u00e8me creuse un tunnel connu sous le nom de H3, d&rsquo;une longueur de 320 m\u00e8tres, il s&rsquo;enfonce \u00e0 25 m\u00e8tres sous la surface. Au d\u00e9but la progression du tunnel est rapide mais avec le temps elle se fait plus lente, d&rsquo;une part le percement est plus dur car en profondeur l&rsquo;on rencontre une couche de craie plus compacte et des silex, d&rsquo;autre part parce qu&rsquo;il faut limiter au maximum les bruits qui r\u00e9sultent d&rsquo;une telle entreprise. En effet des deux c\u00f4t\u00e9s des lignes on creuse, on s&rsquo;\u00e9pie, on place l&rsquo;oreille contre le substrat rocheux pour deviner tout mouvement adverse. Le percement d&rsquo;un nouveau tunnel est parfois d\u00e9tect\u00e9 \u00e0 une distance tr\u00e8s faible, inf\u00e9rieure \u00e0 quinze m\u00e8tres, des charges sont alors plac\u00e9es puis d\u00e9tonn\u00e9es afin d&rsquo;ensevelir les soldats, et de ralentir la progression ennemie. Il arrive m\u00eame qu&rsquo;un sapeur Allemand d\u00e9bouche dans un tunnel Fran\u00e7ais, comme dans la nuit du 8 au 9 mars \u00e0 La Boisselle ou le sapeur c&rsquo;est introduit dans une galerie fran\u00e7aises pleine d&rsquo;explosifs qu&rsquo;il faudra d\u00e9samorcer \u00e0 la h\u00e2te. Ainsi, les sapeurs Anglais se d\u00e9placent avec des sacs de sable sous leurs bottes, ils mouillent la craie pour la rendre plus tendre et d\u00e9collent les silex \u00e0 la ba\u00efonnette. Chaque cailloux prenant place dans un sac de sable afin d&rsquo;\u00eatre \u00e9vacu\u00e9 du tunnel. On d\u00e9ploie des efforts consid\u00e9rables pour rester discret.<br><br>Le percement prend fin sous une fortification de campagne Allemande, la redoute de la cr\u00eate de l&rsquo;aub\u00e9pine, en anglais \u00ab Hawthorn Ridge \u00bb.&nbsp;Les anglais y d\u00e9pose une quantit\u00e9 consid\u00e9rable d&rsquo;explosif, utilis\u00e9 pour la toute premi\u00e8re fois, l&rsquo;ammonal: un m\u00e9lange de nitrates, TNT, et aluminium. Si l&rsquo;ouvrage repr\u00e9sente le plus gros stockage d&rsquo;explosif, il fait partie d&rsquo;un dispositif de 19 mines: 8 grosses et 11 plus petites toutes appel\u00e9es \u00e0 exploser en simultan\u00e9. Parmi les plus grosses charges, on compte Beaumont-Hamel (Hawthorn Ridge), La Boisselle (charges <a href=\"https:\/\/www.lochnagarcrater.org\" target=\"_blank\" rel=\"noreferrer noopener\">Lochnagar<\/a>, Y Sap et Glory Hole), Fricourt (mines Triple Tambour), Bulgar Point et Kasino Point. Les plus petites mines doivent, elles, neutraliser des positions de moindre importance comme les mitrailleuses. Au total, ce sont 18 tonnes d&rsquo;ammonal qui sont plac\u00e9es dans les galeries.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"818\" height=\"1024\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Ancre_sector_1_July_1916-818x1024.png\" alt=\"\" class=\"wp-image-2568\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Ancre_sector_1_July_1916-818x1024.png 818w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Ancre_sector_1_July_1916-240x300.png 240w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Ancre_sector_1_July_1916-768x962.png 768w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Ancre_sector_1_July_1916.png 990w\" sizes=\"auto, (max-width: 818px) 100vw, 818px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Secteur de l&rsquo;Ancre positions Allemandes (en bleu) et Franco-Britanniques (en rouge)<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"923\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/combat.jpg\" alt=\"\" class=\"wp-image-2570\" style=\"width:840px;height:auto\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/combat.jpg 693w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/combat-225x300.jpg 225w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Situation du tunnel H3<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\">L&rsquo;offensive de la Somme d\u00e9buta le samedi 1er juillet 1915, le coup de sifflet \u00e9tant pr\u00e9vu \u00e0 7h28. Le lieutenant g\u00e9n\u00e9ral Sir Aylmer Gould Hunter-Weston demande que la plus grosse mine, celle de la cr\u00eate de l&rsquo;aub\u00e9pine soit d\u00e9clench\u00e9e 8 minutes plus t\u00f4t, afin que les soldats puissent se prot\u00e9ger des d\u00e9bris qui retombent de l&rsquo;explosion. Une action pr\u00e9matur\u00e9e qui va s&rsquo;av\u00e9rer d\u00e9sastreuse et sera qualifi\u00e9e plus tard de \u00ab\u00a0<em>gigantesque erreur<\/em>\u00ab\u00a0.<\/p>\n\n\n\n<p class=\"has-text-align-left\">De cette explosion ph\u00e9nom\u00e9nale, la plus importante de son \u00e9poque et dont on dit qu&rsquo;elle f\u00fbt entendue jusqu&rsquo;a Londres, il nous reste des images. Le cin\u00e9aste <em>Geoffrey Malins<\/em> s&rsquo;est post\u00e9 avec sa cam\u00e9ra \u00e0 800 m\u00e8tres de la cr\u00eate. Au photographe <em>Ernest Brooks<\/em>, on doit aussi une s\u00e9rie de clich\u00e9s de l&rsquo;explosion et du crat\u00e8re qui en r\u00e9sultat.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"956\" height=\"761\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_Ridge.jpg\" alt=\"\" class=\"wp-image-2573\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_Ridge.jpg 956w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_Ridge-300x239.jpg 300w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_Ridge-768x611.jpg 768w\" sizes=\"auto, (max-width: 956px) 100vw, 956px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Explosion de la mine de la cr\u00eate de l&rsquo;aub\u00e9pine (Hawthorn Ridge) par Ernest Brooks<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"750\" src=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_crate-1024x750.jpg\" alt=\"\" class=\"wp-image-2574\" srcset=\"https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_crate-1024x750.jpg 1024w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_crate-300x220.jpg 300w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_crate-768x562.jpg 768w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_crate-1536x1125.jpg 1536w, https:\/\/fromrss.com\/wp-content\/uploads\/2024\/01\/Hawthorn_crate-2048x1500.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Crat\u00e8re de Hawthorn Ridge avec la silhouette du photographe<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"wpex-responsive-embed\"><iframe loading=\"lazy\" title=\"Hawthorn Ridge mine\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/g8YfJmwY5Uo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>L&rsquo;explosion film\u00e9e par Geoffrey Malins<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\">Geoffrez Malins t\u00e9moigne alors :<\/p>\n\n\n\n<p class=\"has-text-align-left\">\u00ab&nbsp;<em>Le terrain o\u00f9 je me tenais a \u00e9t\u00e9 secou\u00e9 par une \u00e9norme convulsion. Le sol a \u00e9t\u00e9 secou\u00e9 et balanc\u00e9. Je me suis agripp\u00e9 \u00e0 mon tr\u00e9pied pour ne pas tomber. Puis, pour tout le monde comme une gigantesque \u00e9ponge, la terre s&rsquo;est expans\u00e9e en l&rsquo;air \u00e0 jusqu&rsquo;\u00e0 une hauteur de centaines de pieds. Elle montait de plus en plus haut, et avec un terrible rugissement la terre broy\u00e9e est retomb\u00e9e sur elle-m\u00eame, ne laissant qu&rsquo;une montagne de fum\u00e9e.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"has-text-align-left\">Trois sections d&rsquo;infanterie Allemande, soit une trentaine d&rsquo;hommes, sont tu\u00e9es sur le coup. D&rsquo;autres dans des tunnels restent pi\u00e9g\u00e9es de part et d&rsquo;autre du crat\u00e8re. La mine explos\u00e9e, c&rsquo;est un v\u00e9ritable d\u00e9luge de feu qui s&rsquo;abat sur les lignes Allemande. Malgr\u00e9 la gigantesque d\u00e9tonation, le chaos et la d\u00e9sorientation qui s&rsquo;en suivent, ce mauvais \u00ab\u00a0timing\u00a0\u00bb, alerte les Allemands sur l&rsquo;imminence d&rsquo;une attaque d&rsquo;infanterie. Il ne leur faut que quelques minutes pour organiser la riposte. Un petit groupe de soldats a pris opportun\u00e9ment position sur le bord de la l\u00e8vre arri\u00e8re du crat\u00e8re qu&rsquo;ils d\u00e9fendent avec une mitrailleuse. Dans un m\u00eame temps, l&rsquo;artillerie pilonne les tranch\u00e9es anglaises. C\u00f4t\u00e9 Britannique, le second bataillon de r\u00e9giment royal des fusillers sort de sa tranch\u00e9e et traverse le no-man&rsquo;s land afin d&rsquo;occuper le crat\u00e8re. Seuls quelques soldats parviennent au bord du crat\u00e8re. Position pour laquelle ils lutteront jusqu&rsquo;\u00e0 midi avant de se faire chasser par la contre-attaque allemande.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Si dans la m\u00e9moire des Fran\u00e7ais, Verdun, bataille qui pr\u00e9c\u00e8de cet \u00e9v\u00e9nement, constitue un point de rep\u00e8re embl\u00e9matique de la premi\u00e8re guerre mondiale, pour les Britanniques, la Somme est un traumatisme. Ce jour est souvent consid\u00e9r\u00e9 comme le plus meurtrier de toute l&rsquo;histoire de l&rsquo;arm\u00e9e Britannique. En ce 1er juillet 1915, les combats ont fait plus de 57 000 bless\u00e9s et 19 000 morts dans les rangs des troupes issues du Commonwealth. La bataille de la Somme se poursuivra jusqu&rsquo;au 18 novembre 1916, entra\u00eenant avec elle, plus d&rsquo;un million de victimes toutes arm\u00e9es confondues et plus de 450 000 morts. Ce qui en fait une des batailles les plus meurtri\u00e8re de l&rsquo;histoire.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Aujourd&rsquo;hui encore, les recherches se poursuivent comme le montre cette \u00e9tude pluridisciplaire du <a href=\"https:\/\/www.tandfonline.com\/doi\/full\/10.1080\/15740773.2023.2297202\" target=\"_blank\" rel=\"noreferrer noopener\">crat\u00e8re de Hawthorn<\/a>. Le propos est aussi illustr\u00e9 au cin\u00e9ma dans le film de 2021 \u00ab\u00a0L&rsquo;enfer sous terre\u00a0\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"wpex-responsive-embed\"><iframe loading=\"lazy\" title=\"L&#039;ENFER SOUS TERRE Bande Annonce VF (2021) Film de Guerre\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/czhrm_0tWVM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption class=\"wp-element-caption\"><em>\u00ab\u00a0L&rsquo;enfer sous terre\u00a0\u00bb bande annonce VF<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-left\">Source &amp; Photos : <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Bataille_de_la_Somme\" target=\"_blank\" rel=\"noreferrer noopener\">La bataille de la Somme<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Beaumont-Hamel\" target=\"_blank\" rel=\"noreferrer noopener\">Beaumont-Hamel<\/a>, <a href=\"https:\/\/www.msn.com\/en-us\/news\/world\/study-reveals-new-details-about-how-the-british-gave-the-germans-the-advantage-on-the-somme\/ar-AA1mHCsZ\">MSN<\/a>, <a href=\"https:\/\/www.geo.fr\/histoire\/bataille-de-la-somme-nouveaux-details-sur-mine-hawthorn-ridge-et-ses-lourdes-consequences-historiques-reveles-par-etude-218313\" target=\"_blank\" rel=\"noreferrer noopener\">Geo<\/a>, <a href=\"https:\/\/fr.news.yahoo.com\/premi\u00e8res-fouilles-crat\u00e8re-hawthorn-ridge-101728201.html\" target=\"_blank\" rel=\"noreferrer noopener\">Yahoo<\/a>, <a href=\"https:\/\/www.westernfrontassociation.com\/world-war-i-articles\/hawthorn-ridge-a-forensic-investigation-into-the-archaeology-and-history-of-hawthorn-crater\/\">The Weste<\/a><a href=\"https:\/\/www.westernfrontassociation.com\/world-war-i-articles\/hawthorn-ridge-a-forensic-investigation-into-the-archaeology-and-history-of-hawthorn-crater\/\" target=\"_blank\" rel=\"noreferrer noopener\">r<\/a><a href=\"https:\/\/www.westernfrontassociation.com\/world-war-i-articles\/hawthorn-ridge-a-forensic-investigation-into-the-archaeology-and-history-of-hawthorn-crater\/\">n Front Association<\/a>, <a href=\"https:\/\/hawthornridgeca.com\/fr\/histoire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hawthorn Ridge Crater Association<\/a>, <a href=\"https:\/\/theconversation.com\/battle-of-the-somme-new-research-shows-detonating-a-massive-mine-under-german-lines-too-early-led-to-a-british-slaughter-220706\" target=\"_blank\" rel=\"noreferrer noopener\">The Conversation<\/a>, <a href=\"https:\/\/dx.doi.org\/10.1080\/15740773.2023.2297202\" target=\"_blank\" rel=\"noreferrer noopener\">Journal of Conflict Archeology<\/a>, <a href=\"https:\/\/cosmosmagazine.com\/history\/archaeology\/world-first-study-of-wwi-battle-site-highlights-british-blunder\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cosmos<\/a>, <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Your browser does not support the audio element. La commune de Beaumont-Hamel&nbsp;dont la toponymie signifie \u00ab\u00a0joli mont pr\u00e8s d&rsquo;un mar\u00e9cage\u00a0\u00bb est un village tranquille d&rsquo;environ 200 habitants en Picardie, dans le d\u00e9partement de la Somme. Il est situ\u00e9 \u00e0 137 kilom\u00e8tres de Paris Notre-Dame. La pr\u00e9sence de l&rsquo;homme y est attest\u00e9e depuis longtemps puisqu&rsquo;on y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2598,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[722,15,17],"tags":[726,734,723,732,736,735,725,730,731,729,733,728,724,727],"class_list":["post-2559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-photographie","category-video","tag-14-18","tag-ammonal","tag-beaumont-hamel","tag-crete-de-laubepine","tag-ernest-brooks","tag-geoffrey-malins","tag-guerre","tag-h3","tag-hawthorn-ridge","tag-joffre","tag-la-boisselle","tag-sapeur","tag-somme","tag-tunnel"],"_links":{"self":[{"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/posts\/2559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/comments?post=2559"}],"version-history":[{"count":26,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/posts\/2559\/revisions"}],"predecessor-version":[{"id":2655,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/posts\/2559\/revisions\/2655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/media\/2598"}],"wp:attachment":[{"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/media?parent=2559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/categories?post=2559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fromrss.com\/index.php\/wp-json\/wp\/v2\/tags?post=2559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}